{"id":286847,"date":"2024-09-06T09:57:50","date_gmt":"2024-09-06T07:57:50","guid":{"rendered":"https:\/\/env-datawords-stagingpro.kinsta.cloud\/comprendre-la-generation-z-dans-un-monde-multiculturel\/"},"modified":"2026-02-24T13:35:17","modified_gmt":"2026-02-24T12:35:17","slug":"comprendre-la-generation-z-dans-un-monde-multiculturel","status":"publish","type":"post","link":"https:\/\/datawords.com\/fr-lu\/comprendre-la-generation-z-dans-un-monde-multiculturel\/","title":{"rendered":"Comprendre la g\u00e9n\u00e9ration Z dans un monde multiculturel"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"286847\" class=\"elementor elementor-286847 elementor-137583\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e70ca41 hero-section e-flex e-con-boxed e-con e-child\" data-id=\"e70ca41\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4321b51 e-con-full e-flex e-con e-child\" data-id=\"4321b51\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd6f3ad textchange elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"cd6f3ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tComprendre la g\u00e9n\u00e9ration Z <br><strong>dans un monde multiculturel<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-334d277 textchange elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"334d277\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Comprendre la g\u00e9n\u00e9ration Z <strong>dans un monde multiculturel<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8225eb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8225eb0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89a78c9\" data-id=\"89a78c9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-953a713 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"953a713\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9b6cb30\" data-id=\"9b6cb30\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85574f1 elementor-widget elementor-widget-image-box\" data-id=\"85574f1\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">L\u2019expression \u201cG\u00e9n\u00e9ration Z\u201d d\u00e9signe les personnes n\u00e9es entre 1995 et 2010. Les marques montrent depuis peu un int\u00e9r\u00eat grandissant pour ces jeunes.<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-643c49f elementor-widget elementor-widget-image-box\" data-id=\"643c49f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Aux \u00c9tats-Unis, la g\u00e9n\u00e9ration Z a d\u00e9j\u00e0 d\u00e9pass\u00e9 les millennials (61 millions contre 60 millions). Selon la National Retail Federation, la g\u00e9n\u00e9ration Z repr\u00e9sente un pouvoir d\u2019achat de 44 milliards de dollars.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f83492 elementor-widget elementor-widget-image-box\" data-id=\"7f83492\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">En Chine, la g\u00e9n\u00e9ration Z est le r\u00e9sultat de la politique de l\u2019enfant unique. D\u2019ailleurs, on ne parle pas de g\u00e9n\u00e9ration Z en Chine, mais on distingue les personnes n\u00e9es entre 1990 et 2000 (90\u540e) et celles n\u00e9es en 2000 (00\u540e) ou apr\u00e8s. Il existe aujourd\u2019hui 230 millions de personnes n\u00e9es entre 1990 et 2000, et 146 millions de personnes n\u00e9es en 2000 ou apr\u00e8s.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90edb95 elementor-widget elementor-widget-image-box\" data-id=\"90edb95\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Ce que vous ignorez peut-\u00eatre, c\u2019est que les pr\u00e9f\u00e9rences et le comportement des consommateurs de la g\u00e9n\u00e9ration Z sur les sites e-commerce varient d\u2019un pays \u00e0 l\u2019autre.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b71b151 elementor-widget elementor-widget-image-box\" data-id=\"b71b151\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Voici cinq points essentiels \u00e0 conna\u00eetre sur la g\u00e9n\u00e9ration Z:<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e51a678 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e51a678\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9de7e9b\" data-id=\"9de7e9b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-82b703f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"82b703f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-427132b\" data-id=\"427132b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9535ed elementor-widget__width-inherit textchange elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"a9535ed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>1. La g\u00e9n\u00e9ration Z est n\u00e9e avec<\/strong> le t\u00e9l\u00e9phone \u00e0 la main<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d3d7f3 elementor-widget__width-inherit textchange elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"2d3d7f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>1. La g\u00e9n\u00e9ration Z est n\u00e9e avec<\/strong><br \/>le t\u00e9l\u00e9phone \u00e0 la main<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0f41e1 elementor-widget elementor-widget-image-box\" data-id=\"e0f41e1\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Lorsque vous ciblez des clients issus de la g\u00e9n\u00e9ration Z, d\u00e9veloppez une version mobile de votre page Web et une application plut\u00f4t qu\u2019un site e-commerce. La g\u00e9n\u00e9ration Z n\u2019est pas seulement une g\u00e9n\u00e9ration d\u2019enfants du num\u00e9rique mais aussi une g\u00e9n\u00e9ration qui utilise davantage le t\u00e9l\u00e9phone mobile. La strat\u00e9gie digitale de votre marque doit privil\u00e9gier les versions mobiles et vos exp\u00e9riences utilisateurs doivent prendre en compte l\u2019exp\u00e9rience mobile des consommateurs de la g\u00e9n\u00e9ration Z. Cet argument est d\u2019autant plus important en Chine, o\u00f9 sur 800 millions d\u2019internautes, 98 % surfent sur Internet via leur t\u00e9l\u00e9phone portable !<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fbdc44 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fbdc44\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e6a2a0c\" data-id=\"e6a2a0c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-131b4f5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"131b4f5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ba498e9\" data-id=\"ba498e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c2e5b2 elementor-widget__width-inherit textchange elementor-widget elementor-widget-text-editor\" data-id=\"3c2e5b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>2. Ne n\u00e9gligez pas les<\/strong><br \/>magasins physiques<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93f4aa2 elementor-widget elementor-widget-image-box\" data-id=\"93f4aa2\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Si vous pensiez que la g\u00e9n\u00e9ration Z ne jurait que par les \u00e9crans, vous vous trompiez ! La g\u00e9n\u00e9ration Z a beau \u00eatre n\u00e9e \u00e0 l\u2019\u00e8re du digital, elle appr\u00e9cie particuli\u00e8rement de pouvoir se rendre en personne dans les magasins. En effet, 80 % des achats effectu\u00e9s par les consommateurs issus de la g\u00e9n\u00e9ration Z sont influenc\u00e9s par les r\u00e9seaux sociaux, notamment par Instagram. Les consommateurs issus de la g\u00e9n\u00e9ration Z aiment toujours autant se rendre en magasin pour acheter leurs produits de beaut\u00e9. 76 % des acheteurs de la g\u00e9n\u00e9ration Z pensent que, m\u00eame s\u2019ils d\u00e9couvrent la marque et les produits sur les r\u00e9seaux sociaux, se rendre en boutique leur procure une meilleure exp\u00e9rience d\u2019achat. La g\u00e9n\u00e9ration Z recherche donc une exp\u00e9rience d\u2019achat unique et vari\u00e9e.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58aed2c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58aed2c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b70cc6\" data-id=\"3b70cc6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-063ec0c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"063ec0c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e1165fb\" data-id=\"e1165fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8496f2c elementor-widget__width-inherit textchange elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"8496f2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>3. Les r\u00e9seaux sociaux pr\u00e9f\u00e9r\u00e9s<\/strong> de la g\u00e9n\u00e9ration Z<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04d8c5f elementor-widget__width-inherit textchange elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"04d8c5f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>3. Les r\u00e9seaux sociaux pr\u00e9f\u00e9r\u00e9s<\/strong><br \/>de la g\u00e9n\u00e9ration Z<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85fef5c elementor-widget elementor-widget-image-box\" data-id=\"85fef5c\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">La g\u00e9n\u00e9ration Z se sert peu de Facebook, consid\u00e9r\u00e9 comme le r\u00e9seau social utilis\u00e9 par leurs parents. Les r\u00e9seaux sociaux les plus populaires chez les Am\u00e9ricains issus de la g\u00e9n\u00e9ration Z sont Instagram (64,59 %), Snapchat (51,31 %) et YouTube (62,48 %), alors qu\u2019en Chine, Douyin (Tiktok), RED et bilibili sont les plateformes les plus en vogue. La g\u00e9n\u00e9ration Z consomme et cr\u00e9e du contenu diff\u00e9remment d\u2019un pays \u00e0 l\u2019autre : votre strat\u00e9gie digitale doit prendre en compte toutes ces particularit\u00e9s.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f47f98b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f47f98b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c9413e\" data-id=\"1c9413e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-454b135 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"454b135\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-57304a1\" data-id=\"57304a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bccc8b elementor-widget__width-inherit textchange elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"4bccc8b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>4. La g\u00e9n\u00e9ration Z aime les marques<\/strong> avec des valeurs<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90a51c3 elementor-widget__width-inherit textchange elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"90a51c3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>4. La g\u00e9n\u00e9ration Z aime les marques<\/strong><br \/>avec des valeurs<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7a49bd elementor-widget elementor-widget-image-box\" data-id=\"f7a49bd\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Aux \u00c9tats-Unis, les \u00ab baby boomers \u00bb ont grandi \u00e0 une \u00e9poque o\u00f9 l\u2019\u00e9conomie \u00e9tait en pleine croissance ; les millenials \u2013 premi\u00e8re g\u00e9n\u00e9ration \u00e0 exp\u00e9rimenter une vie plus difficile que celle de leurs parents \u2013 sont quant \u00e0 eux n\u00e9s \u00e0 une p\u00e9riode d\u2019abondance. En revanche, la g\u00e9n\u00e9ration Z a grandi entour\u00e9e de sujets pr\u00e9occupants tels que le changement climatique, la r\u00e9cession \u00e9conomique ou encore l\u2019in\u00e9galit\u00e9. Elle a donc d\u00e9velopp\u00e9 un plus grand sens des responsabilit\u00e9s et aura tendance \u00e0 d\u00e9fendre des valeurs fortes. La g\u00e9n\u00e9ration Z est pr\u00eate \u00e0 payer un prix plus \u00e9lev\u00e9 si les marques d\u00e9fendent des valeurs telles que le d\u00e9veloppement durable, la protection des animaux ou l\u2019alimentation biologique. Cette tendance n\u2019est pas seulement visible aux \u00c9tats-Unis mais \u00e9galement \u00e0 l\u2019\u00e9chelle mondiale.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f59c21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f59c21\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a70d60b\" data-id=\"a70d60b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-187b752 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"187b752\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6c24aba\" data-id=\"6c24aba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6772f4 elementor-widget__width-inherit textchange elementor-widget elementor-widget-text-editor\" data-id=\"d6772f4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>5. Changez <\/strong><br>d\u2019esth\u00e9tique<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5afee9c elementor-widget elementor-widget-image-box\" data-id=\"5afee9c\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">En Chine, l\u2019industrie cosm\u00e9tique pour homme est en plein essor. Un homme sur cinq n\u00e9 apr\u00e8s 1995 utilise r\u00e9guli\u00e8rement des BB cr\u00e8mes et des rouges \u00e0 l\u00e8vres. Sur le site Tmall, les ventes de crayons \u00e0 sourcils, rouges \u00e0 l\u00e8vres et BB cr\u00e8mes pour hommes ont respectivement augment\u00e9 de 214 %, 278 % et 145 %. Gr\u00e2ce \u00e0 la technologie et \u00e0 l\u2019utilisation des donn\u00e9es, la g\u00e9n\u00e9ration Z est plus friande de personnalisation que les g\u00e9n\u00e9rations pr\u00e9c\u00e9dentes.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-8e68206 e-flex e-con-boxed e-con e-parent\" data-id=\"8e68206\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-69deed1 e-con-full e-flex e-con e-child\" data-id=\"69deed1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ae88b1 elementor-widget elementor-widget-heading\" data-id=\"6ae88b1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ne redoutez pas la g\u00e9n\u00e9ration Z mais ne les excluez pas de votre strat\u00e9gie de marketing digital ! Si vous souhaitez en savoir plus pour cibler cette g\u00e9n\u00e9ration de consommateurs sur diff\u00e9rents march\u00e9s, n\u2019h\u00e9sitez pas \u00e0 vous adresser \u00e0 notre contact Datawords Group ou \u00e0 vous rapprocher de\u00a0notre centre de contact.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aux \u00c9tats-Unis, la g\u00e9n\u00e9ration Z a d\u00e9j\u00e0 d\u00e9pass\u00e9 les millennials (61 millions contre 60 millions). Selon la National Retail Federation, la g\u00e9n\u00e9ration Z repr\u00e9sente un pouvoir d\u2019achat de 44 milliards de dollars.<\/p>\n","protected":false},"author":42,"featured_media":137585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[812],"tags":[],"class_list":["post-286847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insight-nl"],"acf":[],"_links":{"self":[{"href":"https:\/\/datawords.com\/fr-lu\/wp-json\/wp\/v2\/posts\/286847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/datawords.com\/fr-lu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/datawords.com\/fr-lu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/datawords.com\/fr-lu\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/datawords.com\/fr-lu\/wp-json\/wp\/v2\/comments?post=286847"}],"version-history":[{"count":0,"href":"https:\/\/datawords.com\/fr-lu\/wp-json\/wp\/v2\/posts\/286847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/datawords.com\/fr-lu\/wp-json\/wp\/v2\/media\/137585"}],"wp:attachment":[{"href":"https:\/\/datawords.com\/fr-lu\/wp-json\/wp\/v2\/media?parent=286847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/datawords.com\/fr-lu\/wp-json\/wp\/v2\/categories?post=286847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/datawords.com\/fr-lu\/wp-json\/wp\/v2\/tags?post=286847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}