{"id":154372,"date":"2024-11-25T11:42:46","date_gmt":"2024-11-25T10:42:46","guid":{"rendered":"https:\/\/env-datawords-stagingpro.kinsta.cloud\/une-methode-choisie-par-tods-korea-pour-utiliser-differentes-techniques-de-marketing-digital-en-coree\/"},"modified":"2025-11-14T09:44:04","modified_gmt":"2025-11-14T08:44:04","slug":"tods-corea-estrategia-de-marketing-digital-innovadora-basada-en-la-emocion","status":"publish","type":"post","link":"https:\/\/datawords.com\/es-mx\/tods-corea-estrategia-de-marketing-digital-innovadora-basada-en-la-emocion\/","title":{"rendered":"Un m\u00e9todo elegido por Tod&#8217;s Corea para utilizar diferentes t\u00e9cnicas de marketing digital en Corea"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"154372\" class=\"elementor elementor-154372 elementor-153011\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2bef7c2 hero-production e-flex e-con-boxed e-con e-parent\" data-id=\"2bef7c2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fc85ba7 e-con-full e-flex e-con e-child\" data-id=\"fc85ba7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d406320 elementor-widget elementor-widget-image\" data-id=\"d406320\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"358\" height=\"118\" src=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/tods-3.png\" class=\"attachment-full size-full wp-image-281191\" alt=\"\" srcset=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/tods-3.png 358w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/tods-3-300x99.png 300w\" sizes=\"(max-width: 358px) 100vw, 358px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c5a5aa textchange elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"7c5a5aa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><strong>C\u00f3mo Tod\u2019s activ\u00f3 su <\/strong>\n<br>estrategia digital en Corea<\/br><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3869092 textchange elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"3869092\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><strong>C\u00f3mo Tod\u2019s activ\u00f3 su <\/strong>\n<br>estrategia digital en Corea<\/br><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c2c40b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c2c40b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2e1932\" data-id=\"f2e1932\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6afbed4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6afbed4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-260f6f7\" data-id=\"260f6f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2aae9cc e-con-full e-flex e-con e-parent\" data-id=\"2aae9cc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa4d394 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"aa4d394\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Industria<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aeabc05 elementor-widget elementor-widget-heading\" data-id=\"aeabc05\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Lujo<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06f5780 e-con-full e-flex e-con e-parent\" data-id=\"06f5780\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b935782 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b935782\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servicio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-577d9dd elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"577d9dd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Despliegue de todo tipo de contenidos<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59d93e5 miche_shadow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59d93e5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a7c2127\" data-id=\"a7c2127\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-21428d4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"21428d4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5dc4c3b\" data-id=\"5dc4c3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccaf356 elementor-widget elementor-widget-image-box\" data-id=\"ccaf356\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">La firma de moda italiana Tod's ha utilizado un gran n\u00famero de t\u00e9cnicas de marketing para atraer a los millennials y a la generaci\u00f3n Z, generaciones que se adaptan r\u00e1pidamente a las nuevas tendencias. Descubra c\u00f3mo los profesionales de marketing de Datawords despertaron el inter\u00e9s de los clientes utilizando canales locales como KakaoTalk y Naver, as\u00ed como un filtro de realidad aumentada en Instagram.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61c6b48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61c6b48\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b79e507\" data-id=\"b79e507\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-10648b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10648b8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6b79699\" data-id=\"6b79699\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f91fb70 e-con-full e-flex e-con e-parent\" data-id=\"f91fb70\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a640cc6 textchange elementor-widget__width-inherit elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"a640cc6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>el<\/strong> DESAF\u00cdO<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c22048 textchange elementor-widget__width-inherit elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"1c22048\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>el<\/strong> <br>DESAF\u00cdO<\/br><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ca9de8e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ca9de8e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3b4595d\" data-id=\"3b4595d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af6e2eb elementor-widget elementor-widget-image-box\" data-id=\"af6e2eb\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Tod's Corea detect\u00f3 que exist\u00eda la necesidad de t\u00e9cnicas de marketing digital para comunicarse con los clientes locales tanto en l\u00ednea como sin conexi\u00f3n, y para ayudar a la marca a ofrecer productos fruto de una labor artesanal excepcional en Corea de forma m\u00e1s eficaz.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1edadb1 elementor-widget elementor-widget-image-box\" data-id=\"1edadb1\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Por ello, Tod's Corea quer\u00eda trabajar con una agencia internacional con amplia experiencia en marketing localizado para marcas de lujo en Corea y que al mismo tiempo fuera capaz de comunicarse eficazmente con su sede central en Italia.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a87ada notre_reponse elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a87ada\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb97d84\" data-id=\"eb97d84\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-22a9210 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22a9210\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-251773d\" data-id=\"251773d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be1bd77 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"be1bd77\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1204\" height=\"582\" src=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Rectangle-108-2-4.png\" class=\"attachment-full size-full wp-image-281066\" alt=\"\" srcset=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Rectangle-108-2-4.png 1204w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Rectangle-108-2-4-300x145.png 300w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Rectangle-108-2-4-1024x495.png 1024w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Rectangle-108-2-4-768x371.png 768w\" sizes=\"(max-width: 1204px) 100vw, 1204px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b82bb2 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"0b82bb2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"330\" height=\"351\" src=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Rectangle-108-20-3.png\" class=\"attachment-full size-full wp-image-281091\" alt=\"\" srcset=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Rectangle-108-20-3.png 330w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Rectangle-108-20-3-282x300.png 282w\" sizes=\"(max-width: 330px) 100vw, 330px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e0ef12a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0ef12a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6d6fc90\" data-id=\"6d6fc90\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83eb0a1 e-con-full e-flex e-con e-parent\" data-id=\"83eb0a1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c0a4bc textchange elementor-widget__width-inherit elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"0c0a4bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>nuestra<\/strong> respuesta<\/h2> \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04ddad1 textchange elementor-widget__width-inherit elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"04ddad1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>nuestra<\/strong> <br>respuesta<\/br><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f49cedf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f49cedf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-02607de\" data-id=\"02607de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f592360 elementor-widget elementor-widget-image-box\" data-id=\"f592360\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Gracias a su amplia experiencia con numerosas marcas de moda de lujo y a un plan de marketing preciso, Datawords logr\u00f3 establecer una colaboraci\u00f3n en materia de marketing digital con Tod\u2019s Corea.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6162e72 elementor-widget elementor-widget-image-box\" data-id=\"6162e72\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Adem\u00e1s de las campa\u00f1as publicitarias digitales tradicionales, Datawords propuso una serie de campa\u00f1as O2O para que Tod's pudiera diversificar la experiencia de sus clientes.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf59914 our_achievements_case elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf59914\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f8c6507\" data-id=\"f8c6507\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3dc8401 e-con-full e-flex e-con e-parent\" data-id=\"3dc8401\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6f15e55 e-con-full e-flex e-con e-child\" data-id=\"6f15e55\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1fb3309 e-con-full e-flex e-con e-child\" data-id=\"1fb3309\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7708860 elementor-widget elementor-widget-image\" data-id=\"7708860\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"590\" height=\"591\" src=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Rectangle-128-16-2.png\" class=\"attachment-full size-full wp-image-281116\" alt=\"\" srcset=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Rectangle-128-16-2.png 590w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Rectangle-128-16-2-300x300.png 300w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Rectangle-128-16-2-150x150.png 150w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fe6f04 cases-slider e-con-full e-flex e-con e-child\" data-id=\"4fe6f04\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0cc9646 e-con-full e-flex e-con e-child\" data-id=\"0cc9646\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f404096 e-con-full e-flex e-con e-child\" data-id=\"f404096\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a6ef58 elementor-widget elementor-widget-image\" data-id=\"3a6ef58\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"284\" src=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Frame-936-13-2.png\" class=\"attachment-full size-full wp-image-281141\" alt=\"\" srcset=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Frame-936-13-2.png 283w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Frame-936-13-2-150x150.png 150w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64cf295 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"64cf295\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-116e269 elementor-widget elementor-widget-image\" data-id=\"116e269\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"284\" src=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Frame-952-13-2.png\" class=\"attachment-full size-full wp-image-281166\" alt=\"\" srcset=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Frame-952-13-2.png 283w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/10\/Frame-952-13-2-150x150.png 150w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-900151c e-con-full swiper-slider e-flex e-con e-child\" data-id=\"900151c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f65ddf textchange elementor-widget elementor-widget-text-editor\" data-id=\"7f65ddf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tC\u00f3mo Tod\u2019s activ\u00f3 su <strong> estrategia digital en Corea<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df04b2e resultshade elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df04b2e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc111fe\" data-id=\"fc111fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f2d261a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2d261a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-63b1ecd\" data-id=\"63b1ecd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5eec48 e-con-full e-flex e-con e-parent\" data-id=\"d5eec48\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3487ad0 textchange elementor-widget__width-inherit elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"3487ad0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Los<\/strong> resultados<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8191fec textchange elementor-widget__width-inherit elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"8191fec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Los<\/strong>\n<br>resultados<\/br><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d6b3d4c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d6b3d4c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a6d9a9e\" data-id=\"a6d9a9e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83878be elementor-widget elementor-widget-image-box\" data-id=\"83878be\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">M\u00e1s all\u00e1 de las campa\u00f1as publicitarias cl\u00e1sicas en Navier y Kakao, Datawords aplic\u00f3 diversas t\u00e9cnicas de marketing. Adem\u00e1s de hacer publicidad sobre las boutiques ef\u00edmeras f\u00edsicas de Tod's, Datawords cre\u00f3 emoticonos y cupones de emoticonos para aumentar el n\u00famero de seguidores del canal KakaoTalk de Tod's. Este esfuerzo dio como resultado un aumento significativo del n\u00famero de seguidores.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb6d059 elementor-widget elementor-widget-image-box\" data-id=\"eb6d059\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Datawords tambi\u00e9n cre\u00f3 un filtro de realidad aumentada en Instagram a trav\u00e9s de WHATSQUARE, una filial de Datawords, para promocionar eficazmente la marca entre los clientes de Corea y del resto del mundo.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4864ec4 elementor-widget elementor-widget-image-box\" data-id=\"4864ec4\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">El n\u00famero de seguidores de Tod's Corea en KakaoTalk pas\u00f3 de 50 000 antes de la campa\u00f1a a 120 000 despu\u00e9s, lo que supone un aumento de unos 72 000 seguidores. El filtro de realidad aumentada permiti\u00f3 reflejar de forma original el esp\u00edritu italiano de la marca, y el proyecto fue un gran \u00e9xito.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8476944 elementor-widget elementor-widget-image-box\" data-id=\"8476944\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Gracias a la campa\u00f1a de emoticonos en KakaoTalk para Tod's Corea, muchas otras marcas de lujo pidieron a Datawords que les creara emoticonos, lo que permiti\u00f3 a Datawords aumentar la satisfacci\u00f3n de los clientes en funci\u00f3n de su experiencia. En el futuro, Datawords tiene la intenci\u00f3n de seguir utilizando m\u00e9todos de marketing digital innovadores y creativos.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Descubra la historia de \u00e9xito de Tod&#8217;s en Corea del Sur. KakaoTalk, Naver e Instagram: nuevos canales para captar la atenci\u00f3n de los millennials y la generaci\u00f3n Z.<\/p>\n","protected":false},"author":42,"featured_media":253252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[839],"tags":[],"class_list":["post-154372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-case-es-mx"],"acf":[],"_links":{"self":[{"href":"https:\/\/datawords.com\/es-mx\/wp-json\/wp\/v2\/posts\/154372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/datawords.com\/es-mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/datawords.com\/es-mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/datawords.com\/es-mx\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/datawords.com\/es-mx\/wp-json\/wp\/v2\/comments?post=154372"}],"version-history":[{"count":0,"href":"https:\/\/datawords.com\/es-mx\/wp-json\/wp\/v2\/posts\/154372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/datawords.com\/es-mx\/wp-json\/wp\/v2\/media\/253252"}],"wp:attachment":[{"href":"https:\/\/datawords.com\/es-mx\/wp-json\/wp\/v2\/media?parent=154372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/datawords.com\/es-mx\/wp-json\/wp\/v2\/categories?post=154372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/datawords.com\/es-mx\/wp-json\/wp\/v2\/tags?post=154372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}