{"id":154179,"date":"2024-11-25T11:42:46","date_gmt":"2024-11-25T10:42:46","guid":{"rendered":"https:\/\/env-datawords-stagingpro.kinsta.cloud\/une-methode-choisie-par-tods-korea-pour-utiliser-differentes-techniques-de-marketing-digital-en-coree\/"},"modified":"2026-02-03T11:13:30","modified_gmt":"2026-02-03T10:13:30","slug":"tods-korea-innovative-emotion-based-digital-marketing-strategy","status":"publish","type":"post","link":"https:\/\/datawords.com\/en-uk\/tods-korea-innovative-emotion-based-digital-marketing-strategy\/","title":{"rendered":"A method chosen by Tod&#8217;s Korea to make use of various dierent digital marketing techniques in Korea"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"154179\" class=\"elementor elementor-154179 elementor-153011\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e6d4f0e hero-production e-flex e-con-boxed e-con e-parent\" data-id=\"e6d4f0e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8ca9c49 e-con-full e-flex e-con e-child\" data-id=\"8ca9c49\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a661dd9 elementor-widget elementor-widget-image\" data-id=\"a661dd9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"358\" height=\"118\" src=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/tods-2.png\" class=\"attachment-full size-full wp-image-237068\" alt=\"\" srcset=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/tods-2.png 358w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/tods-2-300x99.png 300w\" sizes=\"(max-width: 358px) 100vw, 358px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b65e06 textchange elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"1b65e06\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>HOW TOD&#8217;S IMPLEMENTED ITS \u2028<\/strong><br> DIGITAL STRATEGY IN KOREA\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a8d704 textchange elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"9a8d704\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>HOW TOD&#8217;S IMPLEMENTED ITS <\/strong> DIGITAL STRATEGY IN KOREA\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fe48db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8fe48db\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f4cff2\" data-id=\"1f4cff2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-48aaffb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"48aaffb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8bf63db\" data-id=\"8bf63db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-902f16a e-con-full e-flex e-con e-parent\" data-id=\"902f16a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2564d27 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"2564d27\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Industry<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ced987 elementor-widget elementor-widget-heading\" data-id=\"8ced987\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Luxury<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3db3a52 e-con-full e-flex e-con e-parent\" data-id=\"3db3a52\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-905f524 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"905f524\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Service<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f9f698 elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"6f9f698\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Brand content deployment<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac9e05b miche_shadow elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac9e05b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2e6aa0\" data-id=\"b2e6aa0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bdf63d4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bdf63d4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c8161d8\" data-id=\"c8161d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8bb10bf elementor-widget elementor-widget-image-box\" data-id=\"8bb10bf\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Tod\u2019s, an Italian fashion brand, used many of the latest marketing techniques to draw the attention of millenials and Generation Z, who are quick to adapt to new trends. Find out how the professional marketers at Datawords attracted the interest of customers using local channels like KakaoTalk and Naver alongside an AR filter on Instagram.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2080914 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2080914\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bec64b2\" data-id=\"bec64b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ffb0d0c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ffb0d0c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0aaf1a9\" data-id=\"0aaf1a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a52819 e-con-full e-flex e-con e-parent\" data-id=\"3a52819\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4261da textchange elementor-widget__width-inherit elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"e4261da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>The<\/strong>\u00a0Challenge<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ded7d20 textchange elementor-widget__width-inherit elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"ded7d20\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>The<\/strong><br>\nChallenge<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6e646ea elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6e646ea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d2260ec\" data-id=\"d2260ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ecc77a elementor-widget elementor-widget-image-box\" data-id=\"6ecc77a\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Tod\u2019s Korea realized the need for digital marketing techniques that could be used to communicate with local customers both online and offline and help the brand sell artisanal products of outstanding quality in Korea more effectively.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ad809a elementor-widget elementor-widget-image-box\" data-id=\"6ad809a\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Accordingly, Tod\u2019s Korea sought out a global agency that had plenty of localized marketing experience for luxury brands in Korea and could communicate fluently with its head office in Italy.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb9e270 notre_reponse elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb9e270\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-991db2e\" data-id=\"991db2e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e450810 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e450810\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e986192\" data-id=\"e986192\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac93514 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"ac93514\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1204\" height=\"582\" src=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Rectangle-108-2-1-2.png\" class=\"attachment-full size-full wp-image-237143\" alt=\"\" srcset=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Rectangle-108-2-1-2.png 1204w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Rectangle-108-2-1-2-300x145.png 300w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Rectangle-108-2-1-2-1024x495.png 1024w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Rectangle-108-2-1-2-768x371.png 768w\" sizes=\"(max-width: 1204px) 100vw, 1204px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-926de9a elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"926de9a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"330\" height=\"351\" src=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Rectangle-108-20-2.png\" class=\"attachment-full size-full wp-image-237168\" alt=\"\" srcset=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Rectangle-108-20-2.png 330w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Rectangle-108-20-2-282x300.png 282w\" sizes=\"(max-width: 330px) 100vw, 330px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e07bbbb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e07bbbb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f4c44b0\" data-id=\"f4c44b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92f2fb0 e-con-full e-flex e-con e-parent\" data-id=\"92f2fb0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6834f21 textchange elementor-widget__width-inherit elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"6834f21\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Our<\/strong>\u00a0response<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4f000b textchange elementor-widget__width-inherit elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"a4f000b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Our<\/strong><br>\nresponse<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2ac3ebc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2ac3ebc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9a80422\" data-id=\"9a80422\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-934cd04 elementor-widget elementor-widget-image-box\" data-id=\"934cd04\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">By presenting numerous references for luxury fashion brands and an accurate marketing plan, Datawords successfully formed a digital marketing partnership with Tod\u2019s Korea.\n\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1044683 elementor-widget elementor-widget-image-box\" data-id=\"1044683\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Alongside standard digital advertisements, Datawords also suggested various O2O campaigns for Tod\u2019s to keep up with the brand\u2019s need to diversify the customer experience.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6698417 our_achievements_case elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6698417\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be5eee2\" data-id=\"be5eee2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02e3e7b e-con-full e-flex e-con e-parent\" data-id=\"02e3e7b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-450713f e-con-full e-flex e-con e-child\" data-id=\"450713f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-65fb7c4 e-con-full e-flex e-con e-child\" data-id=\"65fb7c4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e20ecb8 elementor-widget elementor-widget-image\" data-id=\"e20ecb8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"590\" height=\"591\" src=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Rectangle-128-16-1-1.png\" class=\"attachment-full size-full wp-image-237194\" alt=\"\" srcset=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Rectangle-128-16-1-1.png 590w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Rectangle-128-16-1-1-300x300.png 300w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Rectangle-128-16-1-1-150x150.png 150w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90e9f22 cases-slider e-con-full e-flex e-con e-child\" data-id=\"90e9f22\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9ee1f3d e-con-full e-flex e-con e-child\" data-id=\"9ee1f3d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6c68b8c e-con-full e-flex e-con e-child\" data-id=\"6c68b8c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ac02f8b elementor-widget elementor-widget-image\" data-id=\"ac02f8b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"284\" src=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Frame-936-13-1-1.png\" class=\"attachment-full size-full wp-image-237219\" alt=\"\" srcset=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Frame-936-13-1-1.png 283w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Frame-936-13-1-1-150x150.png 150w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f71f126 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"f71f126\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad1505e elementor-widget elementor-widget-image\" data-id=\"ad1505e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"284\" src=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Frame-952-13-1-1.png\" class=\"attachment-full size-full wp-image-237244\" alt=\"\" srcset=\"https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Frame-952-13-1-1.png 283w, https:\/\/datawords.com\/wp-content\/uploads\/2025\/08\/Frame-952-13-1-1-150x150.png 150w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-841601b e-con-full swiper-slider e-flex e-con e-child\" data-id=\"841601b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-903a157 textchange elementor-widget elementor-widget-text-editor\" data-id=\"903a157\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>How Tod&#8217;s implemented its<strong> digital strategy in Korea<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-265bac9 resultshade elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"265bac9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f600fe\" data-id=\"2f600fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-da641da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da641da\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-633b848\" data-id=\"633b848\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-04ee640 e-con-full e-flex e-con e-parent\" data-id=\"04ee640\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2762808 textchange elementor-widget__width-inherit elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"2762808\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>The<\/strong> results<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88f4775 textchange elementor-widget__width-inherit elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"88f4775\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>The<\/strong><br>\nresults<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e676f09 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e676f09\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-dee0536\" data-id=\"dee0536\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d3ce56 elementor-widget elementor-widget-image-box\" data-id=\"8d3ce56\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">\n\nIn addition to the standard advertisements on Naver and Kakao, Datawords implemented all sorts of different marketing techniques. While publicizing Tod\u2019s offline pop-up stores, Datawords created Kakao emoticons and emoticon coupons to increase the number of followers on Tod\u2019s KakaoTalk channel. These efforts resulted in a drastic increase in followers.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8d7cbf elementor-widget elementor-widget-image-box\" data-id=\"a8d7cbf\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">\n\nDatawords also created an AR filter for Instagram through WHATSQUARE, a subsidiary of Datawords, to effectively promote the brand concept to customers both within Korea and overseas.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cdfdb5 elementor-widget elementor-widget-image-box\" data-id=\"8cdfdb5\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">The number of followers of Tod\u2019s Korea on KakaoTalk increased from 50,000 before the campaign to 120,000 afterward, totaling an approximate increase of 72,000. The AR filter was deemed to be a witty expression of the typical Italian feel, and the project was a success.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29b3ea1 elementor-widget elementor-widget-image-box\" data-id=\"29b3ea1\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Starting with the KakaoTalk emoticon campaign for Tod\u2019s Korea, many other luxury brands asked Datawords to make their emoticons, and this allowed Datawords to achieve greater customer satisfaction based on experience. Going forward, Datawords is planning to continue utilizing new and creative digital marketing methods.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Discover Tod\u2019s Success Story in South Korea: KakaoTalk, Naver, and Instagram as New Tools to Capture the Attention of Millennials and Gen Z.<\/p>\n","protected":false},"author":42,"featured_media":253248,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[835],"tags":[],"class_list":["post-154179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-case-en-uk"],"acf":[],"_links":{"self":[{"href":"https:\/\/datawords.com\/en-uk\/wp-json\/wp\/v2\/posts\/154179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/datawords.com\/en-uk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/datawords.com\/en-uk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/datawords.com\/en-uk\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/datawords.com\/en-uk\/wp-json\/wp\/v2\/comments?post=154179"}],"version-history":[{"count":0,"href":"https:\/\/datawords.com\/en-uk\/wp-json\/wp\/v2\/posts\/154179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/datawords.com\/en-uk\/wp-json\/wp\/v2\/media\/253248"}],"wp:attachment":[{"href":"https:\/\/datawords.com\/en-uk\/wp-json\/wp\/v2\/media?parent=154179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/datawords.com\/en-uk\/wp-json\/wp\/v2\/categories?post=154179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/datawords.com\/en-uk\/wp-json\/wp\/v2\/tags?post=154179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}